{"id":69924,"date":"2020-09-29T00:00:00","date_gmt":"2020-09-29T00:00:00","guid":{"rendered":"https:\/\/vipexperiences.mx\/together-apart-street-art-la-innovadora-propuesta-de-stella-artois\/"},"modified":"2020-09-29T00:00:00","modified_gmt":"2020-09-29T00:00:00","slug":"together-apart-street-art-la-innovadora-propuesta-de-stella-artois","status":"publish","type":"post","link":"https:\/\/vipexperiences.mx\/pt\/2020\/09\/29\/together-apart-street-art-la-innovadora-propuesta-de-stella-artois\/","title":{"rendered":"Together Apart Street Art, la innovadora propuesta de Stella Artois"},"content":{"rendered":"<p>Mientras retomamos poco a poco nuestras actividades dentro de los par\u00e1metros de la nueva normalidad, Stella Artois utiliza el arte urbano para ayudar a las personas a reunirse con amigos y seres queridos siempre manteniendo el distanciamiento social, con su campa\u00f1a <strong>Together Apart Street Art<\/strong>.<\/p>\n<p>La cerveza de origen belga con m\u00e1s de 600 a\u00f1os de tradici\u00f3n, <strong>intervendr\u00e1 de una de las colonias m\u00e1s emblem\u00e1ticas de la CDMX, La Condesa, con una obra de arte en el piso, cuyo dise\u00f1o se cre\u00f3 en colaboraci\u00f3n con el equipo creativo de Studio Number One<\/strong>, fundado por el influyente artista Shepard Fairey, cuyo trabajo es reconocible por su estilo altamente gr\u00e1fico y el uso de fuertes bloques de color.<\/p>\n<p>Con el objetivo de garantizar que este momento tan esperado de reconexi\u00f3n sea seguro y agradable, mediante el uso del arte y el dise\u00f1o, Stella Artois espera darles a las personas la seguridad de que pueden mantener el distanciamiento social fuera de sus hogares &#8211; sin perder la atm\u00f3sfera y el atractivo de disfrutar al aire libre.<\/p>\n<p>\u201c<strong>Con la iniciativa Together Apart Street Art estamos usando el arte para unir a las personas de manera segura y original.<\/strong> El distanciamiento social no tiene que ser antisocial. Usando el arte urbano podemos asegurarnos de que este momento en el que nos volvemos a reunir sea uno que todav\u00eda podamos saborear\u201d, coment\u00f3 In\u00e9s Garza, Brand Manager de Stella Artois en Grupo Modelo.<\/p>\n<p><strong>Stella Artois ha creado una enorme y colorida obra de arte de 14 x 8 metros en el coraz\u00f3n de la Condesa,<\/strong> conocida por la gran cantidad de caf\u00e9s, librer\u00edas, restaurantes y galer\u00edas, as\u00ed como por su vida cultural y nocturna. La pieza muestra a una mujer con un chalice sonriendo por poder estar juntos nuevamente.<\/p>\n<p>Las figuras geom\u00e9tricas y los colores contrastantes, no solo lo vuelven visualmente atractivo, sino que muestran de manera ingeniosa a la gente d\u00f3nde deben sentarse para mantener el distanciamiento social.<\/p>\n<figure id=\"attachment_16916\" aria-describedby=\"caption-attachment-16916\" style=\"width: 390px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-thumbnail wp-image-16916\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/09\/Stella-Artois_Together-Apart-Street-Art5-400x225.jpg\" alt=\"Stella Artois_Together Apart Street Art5\" width=\"400\" height=\"225\" \/><figcaption id=\"caption-attachment-16916\" class=\"wp-caption-text\">Foto: Stella Artois,<br \/>Together Apart Street Art.<\/figcaption><\/figure>\n<p><strong>Los c\u00edrculos con contraste de color acomodan grupos de diferentes tama\u00f1os<\/strong>, lo que permite que personas de diferentes hogares se re\u00fanan en c\u00edrculos adyacentes, con \u00e1reas m\u00e1s grandes para que varios amigos compartan una cerveza juntos.<\/p>\n<p>El espacio entre los c\u00edrculos cumple con las medidas de 1.5 m para mantener el distanciamiento social, sin embargo, el rango de tama\u00f1os y l\u00edneas fluidas a su alrededor crean una sensaci\u00f3n de libertad y movimiento, evitando la sensaci\u00f3n de estar en una cadr\u00edcula o el sentimiento de desconexi\u00f3n que se encuentra en otros dise\u00f1os de distanciamiento social.<\/p>\n<p><strong>A partir del 2 y hasta el 28 de octubre, en un horario de 11 am a 7 pm, en Av. Sonora 141, esquina con \u00c1msterdam, en la Colonia Condesa, los transe\u00fantes podr\u00e1n disfrutar de este magn\u00edfico arte en el piso<\/strong>, adaptado en M\u00e9xico por Artsynonym, colectivo dedicado a crear redes de trabajo entre artistas.<\/p>\n<p>Stella Artois tendr\u00e1 activaciones durante los fines de semana: cada viernes, s\u00e1bado y domingo la gente podr\u00e1 disfrutar de una refrescante cerveza con amigos y seres queridos, manteniendo el distanciamiento social representado en el arte plasmado en el piso.<\/p>\n<p>Con esta iniciativa, Stella Artois tambi\u00e9n busca atraer un flujo m\u00e1s grande de personas a las colonias Condesa y Roma, apoyando as\u00ed a los restaurantes y bares de la zona que ya est\u00e1n preparados para recibir nuevamente a los comensales con todas las medidas de sanidad establecidas.<\/p>\n<p>El proyecto Together Apart Street Art se ha implementado en diferentes pa\u00edses del mundo, como Reino Unido, Sud\u00e1frica, Canad\u00e1, Estados Unidos, y ahora en M\u00e9xico, para brindar a las personas una experiencia \u00fanica en la que puedan compartir momentos con sus amigos y seres queridos a\u00fan en tiempos de distanciamiento social.<\/p>\n<p><strong>Tamb\u00e9m pode estar interessado em<\/strong><\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/pt\/2020\/09\/24\/drink-factory-aperol-spritz-es-perfecto-para-un-dia-caluroso\/\">DRINK FACTORY: EL APEROL SPRITZ ES PERFECTO PARA UN D\u00cdA CALUROSO<\/a><\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/pt\/2020\/09\/23\/majahuitas-beach-club-el-nuevo-concepto-de-playa-en-vallarta\/\">MAJAHUITAS BEACH CLUB, EL NUEVO CONCEPTO DE PLAYA EN VALLARTA<\/a><\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/pt\/2020\/09\/23\/si-amas-la-carne-tress-prime-es-para-ti\/\">SI AMAS LA CARNE, TRESS PRIME ES PARA TI<\/a><\/p>\n<div class=\"single-title post-title entry-title is-size-1\">\n<p>&nbsp;<\/p>\n<\/div>\n<p><a href=\"https:\/\/vipexperiences.mx\/pt\/2020\/05\/07\/heaven-el-paraiso-en-hard-rock-hotel-riviera-maya\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"alignleft wp-image-14880 size-thumbnail\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/VIP-EXPERIENCES-03-400x365.jpg\" sizes=\"(max-width: 400px) 100vw, 400px\" srcset=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/VIP-EXPERIENCES-03-400x365.jpg 400w, https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/VIP-EXPERIENCES-03-1000x912.jpg 1000w, https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/VIP-EXPERIENCES-03-1600x1459.jpg 1600w, https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/VIP-EXPERIENCES-03-768x700.jpg 768w, https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/VIP-EXPERIENCES-03-1536x1401.jpg 1536w, https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/VIP-EXPERIENCES-03-2048x1867.jpg 2048w\" alt=\"\" width=\"400\" height=\"365\" \/><\/a><\/p>\n<h2 aria-label=\"Concha de conte\u00fado\">FA\u00c7A J\u00c1 A SUA RESERVA! ESTA \u00c9 UMA PROMO\u00c7\u00c3O A N\u00c3O PERDER.<\/h2>\n<h2 aria-label=\"Concha de conte\u00fado\"><img decoding=\"async\" class=\"size-full wp-image-14606 alignleft\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/05\/logo-mini-WA.jpg\" alt=\"\" width=\"49\" height=\"45\" \/><\/h2>\n<h2 aria-label=\"Concha de conte\u00fado\"><a href=\"https:\/\/wa.link\/t9mr0v\" target=\"_blank\" rel=\"noopener\">553056-8075<\/a><\/h2>","protected":false},"excerpt":{"rendered":"<p>Mientras retomamos poco a poco nuestras actividades dentro de los par\u00e1metros de la nueva normalidad, Stella Artois utiliza el arte urbano para ayudar a las personas a reunirse con amigos y seres queridos siempre manteniendo el distanciamiento social, con su campa\u00f1a Together Apart Street Art. La cerveza de origen belga con m\u00e1s de 600 a\u00f1os &#8230; <a title=\"Together Apart Street Art, la innovadora propuesta de Stella Artois\" class=\"read-more\" href=\"https:\/\/vipexperiences.mx\/pt\/2020\/09\/29\/together-apart-street-art-la-innovadora-propuesta-de-stella-artois\/\" aria-label=\"Leia mais sobre Together Apart Street Art, la innovadora propuesta de Stella Artois\">Ler mais<\/a><\/p>","protected":false},"author":1,"featured_media":57755,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[3534,4857,4858,2375,4859,46],"class_list":["post-69924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-grupo-modelo","tag-ines-garza","tag-shepard-fairey","tag-stella-artois","tag-studio-number-one","tag-tendencias"],"uagb_featured_image_src":{"full":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Stella-Artois_Together-Apart-Street-Art-scaled-1-jpg.webp",1600,899,false],"thumbnail":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Stella-Artois_Together-Apart-Street-Art-scaled-1-150x150.webp",150,150,true],"medium":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Stella-Artois_Together-Apart-Street-Art-scaled-1-300x169.webp",300,169,true],"medium_large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Stella-Artois_Together-Apart-Street-Art-scaled-1-768x432.webp",768,432,true],"large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Stella-Artois_Together-Apart-Street-Art-scaled-1-1024x575.webp",1024,575,true],"1536x1536":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Stella-Artois_Together-Apart-Street-Art-scaled-1-1536x863.webp",1536,863,true],"2048x2048":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Stella-Artois_Together-Apart-Street-Art-scaled-1-jpg.webp",1600,899,false],"trp-custom-language-flag":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Stella-Artois_Together-Apart-Street-Art-scaled-1-18x10.webp",18,10,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/vipexperiences.mx\/pt\/author\/soporte_4z6oqe9k\/"},"uagb_comment_info":0,"uagb_excerpt":"Mientras retomamos poco a poco nuestras actividades dentro de los par\u00e1metros de la nueva normalidad, Stella Artois utiliza el arte urbano para ayudar a las personas a reunirse con amigos y seres queridos siempre manteniendo el distanciamiento social, con su campa\u00f1a Together Apart Street Art. La cerveza de origen belga con m\u00e1s de 600 a\u00f1os&hellip;","_links":{"self":[{"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/posts\/69924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/comments?post=69924"}],"version-history":[{"count":0,"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/posts\/69924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/media\/57755"}],"wp:attachment":[{"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/media?parent=69924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/categories?post=69924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipexperiences.mx\/pt\/wp-json\/wp\/v2\/tags?post=69924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}