{"id":71493,"date":"2021-05-07T00:00:00","date_gmt":"2021-05-07T00:00:00","guid":{"rendered":"https:\/\/vipexperiences.mx\/the-vip-dia-de-las-madres-sorprendela-con-esta-receta-de-la-chef-gaby-ruiz\/"},"modified":"2021-05-07T00:00:00","modified_gmt":"2021-05-07T00:00:00","slug":"the-vip-dia-de-las-madres-sorprendela-con-esta-receta-de-la-chef-gaby-ruiz","status":"publish","type":"post","link":"https:\/\/vipexperiences.mx\/it\/2021\/05\/07\/the-vip-dia-de-las-madres-sorprendela-con-esta-receta-de-la-chef-gaby-ruiz\/","title":{"rendered":"The VIP D\u00eda de las Madres: Sorpr\u00e9ndela con esta receta de la chef Gaby Ruiz"},"content":{"rendered":"<p>Para celebrar y consentir a las madres de M\u00e9xico, la chef Gaby Ruiz, embajadora de CAF\u00c9 y nombrada mejor Chef de Me\u0301xico por la revista Gentleman en 2020, comparte una exquisita receta para apapachar a mam\u00e1 con un mole con short rib.<\/p>\n<p>Al respecto, la chef comenta \u201cYo pienso que a mam\u00e1 hay que celebrarla todos los d\u00edas, pero aprovechemos la oportunidad de llenarla de mucho m\u00e1s amor este d\u00eda en especial. \u00bfY qu\u00e9 mejor que con un delicioso platillo preparado por uno mismo? Les recomiendo usar la estufa CAF\u00c9, que cuenta con quemadores que te permiten alcanzar altas y bajas temperaturas. Estoy segura de que dejar\u00e1n encantadas a sus mam\u00e1s preparando un mole desde cero con esta receta que les comparto\u201d.<\/p>\n<h6><strong>Mole con Short Rib<\/strong><\/h6>\n<p><strong>Rinde: 2 porciones<\/strong><\/p>\n<p><strong><u>Para el mole<\/u><\/strong><\/p>\n<ul>\n<li>250 ml aceite vegetal<\/li>\n<li>12 gr chile ancho seco<\/li>\n<li>12 gr chile mulato seco<\/li>\n<li>12 gr chile pasilla seco<\/li>\n<li>4 gr cacahuate sin sal<\/li>\n<li>4 gr nuez pecana<\/li>\n<li>4 gr pepita de calabaza<\/li>\n<li>4 gr almendra entera<\/li>\n<li>4 gr ajonjol\u00ed<\/li>\n<li>22 gr cebolla blanca<\/li>\n<li>72 gr tomillo fresco<\/li>\n<li>43 gr hoja de aguacate fresca<\/li>\n<li>138 gr pl\u00e1tano macho muy maduro<\/li>\n<li>4 gr pasas<\/li>\n<li>2 gr canela entera<\/li>\n<li>1 gr an\u00eds estrella<\/li>\n<li>2 gr clavo de olor entero<\/li>\n<li>Ajo fresco<\/li>\n<li>1 gr or\u00e9gano entero<\/li>\n<li>2 gr pimienta negra<\/li>\n<li>1 gr comino<\/li>\n<li>65 gr chocolate de metate con almendra<\/li>\n<li>405 ml caldo de pollo natural<\/li>\n<\/ul>\n<h6><strong>MOLE PREPARADO:<\/strong><\/h6>\n<ul>\n<li>434 ml caldo de pollo natural<\/li>\n<li>25 gr sal<\/li>\n<li>85 gr az\u00facar refinada<\/li>\n<\/ul>\n<p><strong><u>Procedimiento<\/u><\/strong><\/p>\n<p><strong><u>Pasta de mole:<\/u><\/strong><\/p>\n<ol>\n<li>Retirar el rabo y desvenar los chiles por separado (reservar las semillas), deshidratarlos en el horno a 120\u00baC por 30 min, sin quemar (verificar cada 10 min).<\/li>\n<li>Fre\u00edr los frutos secos por separado sin quemar.<\/li>\n<li>Tostar las semillas de los chiles sin quemar y reservar.<\/li>\n<li>Cortar la cebolla en cubos de tama\u00f1o irregular y limpiar perfectamente las hojas de aguacate.<\/li>\n<li>Pelar el pl\u00e1tano, fre\u00edrlo hasta obtener un color caramelo muy oscuro e intenso. (El pl\u00e1tano macho debe estar completamente negro y muy suave).<\/li>\n<li>En una cacerola fre\u00edr las hojas de olor y las especias (tomillo con ramita, hoja de aguacate, canela, an\u00eds de estrella, clavo de olor, or\u00e9gano, pimienta negra, comino). Las hojas de olor deben adquirir un color verde brillante, en este momento agregar los gajos de cebolla y ajo hasta que est\u00e9n bien sancochadas con una textura muy suave, transparente y de algunos tonos caramelo.<\/li>\n<li>Fre\u00edr las pasas y reservar.<\/li>\n<li>Cortar el chocolate en trozos peque\u00f1os.<\/li>\n<li>En un recipiente grande incorporar todos los elementos y dejar reposar durante una noche.<\/li>\n<\/ol>\n<ul>\n<li>Calentar el caldo de pollo para la pasta de mole. Una vez que el caldo est\u00e9 hirviendo, verterlo a la olla, remover la pala y dejar reposar 15 minutos. Despu\u00e9s de haber reposado, moler la pasta de mole con ayuda de una licuadora hasta obtener una textura muy tersa, fre\u00edr la pasta de mole durante 1 hora aprox. a fuego muy bajo, hasta obtener una masa compacta. Mover constantemente para evitar que se pegue en el fondo y que se integre bien. Una vez obtenida la pasta de mole tapar la olla con papel film y dejar reposar 1 d\u00eda en refrigeraci\u00f3n.<\/li>\n<\/ul>\n<p><strong>Mole preparado:<\/strong><\/p>\n<ul>\n<li>Moler la pasta de mole con caldo de pollo y colar. Debe quedar perfectamente molido para evitar mermar. Cocer el mole hasta que hierva y sazonar con sal y az\u00facar.<\/li>\n<\/ul>\n<h6><strong><u>Para el Short Rib<\/u><\/strong><\/h6>\n<ul>\n<li>5 gr sal de mesa<\/li>\n<li>6 gr az\u00facar refinada<\/li>\n<li>3 gr pimienta negra molida<\/li>\n<li>624 gr short rib sin hueso<\/li>\n<li>70 gr cebolla blanca (troceada 4 cm)<\/li>\n<li>80 gr zanahoria (troceada 4 cm)<\/li>\n<li>5 gr cilantro entero<\/li>\n<li>80 gr jitomate guaje (en 4)<\/li>\n<li>80 gr calabaza italiana (trozoz 4 cm)<\/li>\n<li>1 lt agua<\/li>\n<\/ul>\n<p><strong><u>Procedimiento<\/u><\/strong><\/p>\n<ol>\n<li>Mezclar la sal, el az\u00facar y la pimienta molida.<\/li>\n<li>Limpiar muy bien el short rib y marinar con la mezcla anterior, reposar durante 1 hora.<\/li>\n<li>Sellar en un sart\u00e9n durante 5 min por cada lado, enfriar y dejar reposar en refrigeraci\u00f3n durante una noche.<\/li>\n<li>En una charola honda de metal, hacer una cama de zanahoria, cilantro, tomate, cebolla blanca y calabaza italiana. Colocar el short rib sobre los vegetales.<\/li>\n<li>Agregar agua hasta cubrir. Tapar con vitafilm y papel aluminio. Hornear durante 6 horas a 100\u00baC.<\/li>\n<li>Dejar enfriar y cortar en trozos de 5 mm aprox.<\/li>\n<\/ol>\n<p><strong><u>Para el short rib con pl\u00e1tano<\/u><\/strong><\/p>\n<ul>\n<li>50 gr short rib cocido picado<\/li>\n<li>85 gr pl\u00e1tano macho (pasado) frito<\/li>\n<li>30 gr cebolla blanca brunoise caramelizada<\/li>\n<li>5 gr aceite vegetal<\/li>\n<li>3 gr sal de mesa<\/li>\n<\/ul>\n<p><strong><u>Procedimiento<\/u><\/strong><\/p>\n<ol>\n<li>Pelar el pl\u00e1tano y cortar en cubos de 1 cm y fre\u00edr en aceite a 180\u00baC hasta obtener un caramelizado marr\u00f3n oscuro, escurrir y reservar.<\/li>\n<li>Cortar la cebolla en cubitos y agregar a un sart\u00e9n caliente con aceite vegetal, fre\u00edr hasta obtener un color marr\u00f3n claro.<\/li>\n<li>Agregar el short rib y los pl\u00e1tanos fritos y sazonar con sal, porcionar de 60 gr.<\/li>\n<\/ol>\n<p><strong><u>Para la flor de jamaica<\/u><\/strong><\/p>\n<ul>\n<li>20 gr jamaica seca<\/li>\n<li>800 ml agua<\/li>\n<li>1 gr sal de mesa<\/li>\n<\/ul>\n<p><strong><u>Procedimiento<\/u><\/strong><\/p>\n<ol>\n<li>Cocer la jamaica con la mitad del agua durante 20 min a fuego medio, escurrir la flor de jamaica y cocinar nuevamente con el resto del agua y sal.<\/li>\n<li>Regresar al fuego y cocinar durante 15 min m\u00e1s hasta que la flor est\u00e9 completamente cocida. Escurrir y reservar.<\/li>\n<\/ol>\n<p><strong><u>Para el montaje<\/u><\/strong><\/p>\n<p><strong>Rinde: 2 porciones<\/strong><\/p>\n<ul>\n<li>200 gr mole<\/li>\n<li>120 gr short rib con pl\u00e1tano<\/li>\n<li>32 gr tortilla amarilla<\/li>\n<li>12 gr jamaica cocida<\/li>\n<li>6 gr queso doble crema rallado<\/li>\n<li>4 gr ajonjol\u00ed tostado<\/li>\n<li>12 gr pi\u00f1\u00f3n tostado<\/li>\n<li>15 ml aceite vegetal<\/li>\n<\/ul>\n<p><strong><u>Procedimiento<\/u><\/strong><\/p>\n<ol>\n<li>Pochar la tortilla con aceite vegetal hasta que quede ligeramente dorada.<\/li>\n<li>En un plato semi-hondo agregar un espejo de mole, en el centro montar el short rib con pl\u00e1tano previamente caliente.<\/li>\n<li>Untar mole en la tortilla por ambos lados y colocar sobre el short rib.<\/li>\n<li>Espolvorear queso, pi\u00f1\u00f3n, ajonjol\u00ed y decorar con la flor de jamaica cocida.<\/li>\n<\/ol>\n<p><strong>POTREBBE INTERESSARTI ANCHE:<\/strong><br \/>\n<a href=\"https:\/\/vipexperiences.mx\/it\/2021\/05\/04\/ulysse-nardin-ufo-un-viaje-a-otra-dimension\/\">ULYSSE NARDIN UFO, UN VIAJE A OTRA DIMENSI\u00d3N<\/a><br \/>\n<a href=\"https:\/\/vipexperiences.mx\/it\/2021\/05\/05\/kia-stinger-2022-el-gt-mas-potente-de-la-armadora-coreana\/\">KIA STINGER 2022, EL GT M\u00c1S POTENTE DE LA ARMADORA COREANA<\/a><br \/>\n<a href=\"https:\/\/vipexperiences.mx\/it\/2021\/05\/03\/jacob-co-epic-x-chrono-carbon-forged-limited-edition-mexico-tributo-tricolor\/\">JACOB &amp; CO. EPIC X CHRONO CARBON FORGED LIMITED EDITION MEXICO, TRIBUTO TRICOLOR<\/a><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Para celebrar y consentir a las madres de M\u00e9xico, la chef Gaby Ruiz, embajadora de CAF\u00c9 y nombrada mejor Chef de Me\u0301xico por la revista Gentleman en 2020, comparte una exquisita receta para apapachar a mam\u00e1 con un mole con short rib. Al respecto, la chef comenta \u201cYo pienso que a mam\u00e1 hay que celebrarla &#8230; <a title=\"The VIP D\u00eda de las Madres: Sorpr\u00e9ndela con esta receta de la chef Gaby Ruiz\" class=\"read-more\" href=\"https:\/\/vipexperiences.mx\/it\/2021\/05\/07\/the-vip-dia-de-las-madres-sorprendela-con-esta-receta-de-la-chef-gaby-ruiz\/\" aria-label=\"Per saperne di pi\u00f9 su The VIP D\u00eda de las Madres: Sorpr\u00e9ndela con esta receta de la chef Gaby Ruiz\">Leggi tutto<\/a><\/p>","protected":false},"author":1,"featured_media":63293,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[138,4845,217,3426,7658],"class_list":["post-71493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-chef","tag-gaby-ruiz","tag-mole","tag-monogram","tag-short-rib"],"uagb_featured_image_src":{"full":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Mole-con-Short-Rib_3-scaled-1-jpg.webp",1600,1067,false],"thumbnail":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Mole-con-Short-Rib_3-scaled-1-150x150.webp",150,150,true],"medium":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Mole-con-Short-Rib_3-scaled-1-300x200.webp",300,200,true],"medium_large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Mole-con-Short-Rib_3-scaled-1-768x512.webp",768,512,true],"large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Mole-con-Short-Rib_3-scaled-1-1024x683.webp",1024,683,true],"1536x1536":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Mole-con-Short-Rib_3-scaled-1-1536x1024.webp",1536,1024,true],"2048x2048":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Mole-con-Short-Rib_3-scaled-1-jpg.webp",1600,1067,false],"trp-custom-language-flag":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Mole-con-Short-Rib_3-scaled-1-18x12.webp",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/vipexperiences.mx\/it\/author\/soporte_4z6oqe9k\/"},"uagb_comment_info":0,"uagb_excerpt":"Para celebrar y consentir a las madres de M\u00e9xico, la chef Gaby Ruiz, embajadora de CAF\u00c9 y nombrada mejor Chef de Me\u0301xico por la revista Gentleman en 2020, comparte una exquisita receta para apapachar a mam\u00e1 con un mole con short rib. Al respecto, la chef comenta \u201cYo pienso que a mam\u00e1 hay que celebrarla&hellip;","_links":{"self":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/posts\/71493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/comments?post=71493"}],"version-history":[{"count":0,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/posts\/71493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/media\/63293"}],"wp:attachment":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/media?parent=71493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/categories?post=71493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/tags?post=71493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}