{"id":69325,"date":"2020-07-21T00:00:00","date_gmt":"2020-07-21T00:00:00","guid":{"rendered":"https:\/\/vipexperiences.mx\/ermenegildo-zegna-celebra-110-anos-con-una-coleccion-unica-y-un-desfile-innovador\/"},"modified":"2020-07-21T00:00:00","modified_gmt":"2020-07-21T00:00:00","slug":"ermenegildo-zegna-celebra-110-anos-con-una-coleccion-unica-y-un-desfile-innovador","status":"publish","type":"post","link":"https:\/\/vipexperiences.mx\/it\/2020\/07\/21\/ermenegildo-zegna-celebra-110-anos-con-una-coleccion-unica-y-un-desfile-innovador\/","title":{"rendered":"Ermenegildo Zegna celebra 110 a\u00f1os con una colecci\u00f3n \u00fanica y un desfile innovador"},"content":{"rendered":"<p>A finales de la semana pasada, la casa italiana festej\u00f3 su aniversario con la presentaci\u00f3n de la colecci\u00f3n <a href=\"https:\/\/www.zegna.mx\/mx-es\/revista\/desfile-de-moda\/coleccion-de-verano.html\" target=\"_blank\" rel=\"noopener\"><strong>Ermenegildo Zegna XXX summer 2021<\/strong><\/a>.<\/p>\n<p>Reconocida, no s\u00f3lo por revolucionar la industria de la moda, sino tambi\u00e9n por su impecable sastrer\u00eda, <strong>el concepto de la nueva colecci\u00f3n es \u201cUse The Existing\u201d<\/strong>, para concientizar la responsabilidad social y el cuidado de la naturaleza.<\/p>\n<p>Para respetar esa l\u00ednea,<strong> la pasarela de su 110 aniversario se realiz\u00f3 en Oasi Zegna<\/strong>, el peque\u00f1o pueblo en donde su ubica la marca para fabricar las telas, entre otros procesos de producci\u00f3n.<\/p>\n<figure id=\"attachment_12786\" aria-describedby=\"caption-attachment-12786\" style=\"width: 990px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-12786 size-medium\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/07\/EdI2cQwX0AAxmoa-1000x563.jpeg\" alt=\"\" width=\"1000\" height=\"563\" \/><figcaption id=\"caption-attachment-12786\" class=\"wp-caption-text\">Foto:: Ermenegildo Zegna<\/figcaption><\/figure>\n<p>Sin duda, representa un regreso a sus or\u00edgenes fue la punta de lanza para<strong> un desfile visualmente \u00fanico<\/strong>, en donde los modelos incluso <strong>recorrieron hasta 3.3 kil\u00f3metros<\/strong>, distribuidos entre la f\u00e1brica y paisaje naturales de la locaci\u00f3n.<\/p>\n<p>El desfile tambi\u00e9n se realiz\u00f3 en relaci\u00f3n con el Fashion week de Mil\u00e1n y <strong>se bautiz\u00f3 Hombre-M\u00e1quina-Naturaleza<\/strong>.<\/p>\n<p>En cuanto a las prendas, <strong>la colecci\u00f3n se destaca por la fluidez de sus l\u00edneas y siluetas<\/strong>, que brinda altos vol\u00famenes a cada uno de los outfits.<\/p>\n<figure id=\"attachment_12794\" aria-describedby=\"caption-attachment-12794\" style=\"width: 990px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-12794 size-medium\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/07\/EdW7oTAXYAEBI33-1000x750.jpeg\" alt=\"\" width=\"1000\" height=\"750\" \/><figcaption id=\"caption-attachment-12794\" class=\"wp-caption-text\">Foto: Ermenegildo Zegna<\/figcaption><\/figure>\n<figure id=\"attachment_12789\" aria-describedby=\"caption-attachment-12789\" style=\"width: 990px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-12789 size-medium\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/07\/EdW7gmwWAAMPlfC-1000x750.jpeg\" alt=\"\" width=\"1000\" height=\"750\" \/><figcaption id=\"caption-attachment-12789\" class=\"wp-caption-text\">Foto: Ermenegildo Zegna<\/figcaption><\/figure>\n<figure id=\"attachment_12791\" aria-describedby=\"caption-attachment-12791\" style=\"width: 990px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12791 size-medium\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/07\/EdW7oSMXoAExbI8-1000x750.jpeg\" alt=\"\" width=\"1000\" height=\"750\" \/><figcaption id=\"caption-attachment-12791\" class=\"wp-caption-text\">Foto: Ermenegildo Zegna<\/figcaption><\/figure>\n<p>Los cortes son vers\u00e1tiles, desde hombros ca\u00eddos o cuellos cortos, <strong>hasta bolsillos grandes o gabardinas cortas<\/strong> y capas.<\/p>\n<p>Manteniendo la filosof\u00eda que ide\u00f3 el concepto de la colecci\u00f3n, <strong>se utiliza materia prima como lana, c\u00e1\u00f1amo, seda, entre otras<\/strong>. La colecci\u00f3n se acompa\u00f1a de accesorios atrevidos, como lentes y bolsos.<\/p>\n<p><iframe title=\"Ermenegildo Zegna XXX Summer 2021 Fashion Show\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/H1QoBpZusXk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>TAMBI\u00c9N PODR\u00cdA INTERESARTE:<\/strong><\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/it\/2020\/07\/11\/netflix-estrena-oscuro-deseo-nueva-serie-de-maite-perroni-alejandro-speitzer-y-maria-fernanda-yepes\/\">NETFLIX ESTRENA OSCURO DESEO, NUEVA SERIE DE MAITE PERRONI, ALEJANDRO SPEITZER Y MAR\u00cdA\u00a0 FERNANDA YEPES<\/a><\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/it\/2020\/07\/08\/columna-la-imagen-empresarial-en-tiempos-de-coronavirus\/\">COLUMNA. LA IMAGEN EMPRESARIAL EN TIEMPOS DE CORONAVIRUS<\/a><\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/it\/2020\/07\/17\/entrevista-maria-fernanda-yepes-nos-habla-sobre-oscuro-deseo-la-nueva-serie-original-de-netflix\/\">ENTREVISTA. MAR\u00cdA FERNANDA YEPES HABLA SOBRE OSCURO DESEO, LA NUEVA SERIE ORIGINAL DE NETFLIX<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>A finales de la semana pasada, la casa italiana festej\u00f3 su aniversario con la presentaci\u00f3n de la colecci\u00f3n Ermenegildo Zegna XXX summer 2021. Reconocida, no s\u00f3lo por revolucionar la industria de la moda, sino tambi\u00e9n por su impecable sastrer\u00eda, el concepto de la nueva colecci\u00f3n es \u201cUse The Existing\u201d, para concientizar la responsabilidad social y &#8230; <a title=\"Ermenegildo Zegna celebra 110 a\u00f1os con una colecci\u00f3n \u00fanica y un desfile innovador\" class=\"read-more\" href=\"https:\/\/vipexperiences.mx\/it\/2020\/07\/21\/ermenegildo-zegna-celebra-110-anos-con-una-coleccion-unica-y-un-desfile-innovador\/\" aria-label=\"Per saperne di pi\u00f9 su Ermenegildo Zegna celebra 110 a\u00f1os con una colecci\u00f3n \u00fanica y un desfile innovador\">Leggi tutto<\/a><\/p>","protected":false},"author":1,"featured_media":55453,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[21],"tags":[193,3918,326,2532,1079,2344,971,3919,3920,3921,46,54],"class_list":["post-69325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luxury-lifestyle","tag-aniversario","tag-ermenegildo-zegna","tag-estilo","tag-fashion","tag-lifestyle","tag-medio-ambiente","tag-moda","tag-moda-masculina","tag-pasarela","tag-responsabilidad-social","tag-tendencias","tag-video"],"uagb_featured_image_src":{"full":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/EdI2cQ6XYAAvU57-jpeg.webp",1600,900,false],"thumbnail":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/EdI2cQ6XYAAvU57-150x150.webp",150,150,true],"medium":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/EdI2cQ6XYAAvU57-300x169.webp",300,169,true],"medium_large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/EdI2cQ6XYAAvU57-768x432.webp",768,432,true],"large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/EdI2cQ6XYAAvU57-1024x576.webp",1024,576,true],"1536x1536":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/EdI2cQ6XYAAvU57-1536x864.webp",1536,864,true],"2048x2048":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/EdI2cQ6XYAAvU57-jpeg.webp",1600,900,false],"trp-custom-language-flag":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/EdI2cQ6XYAAvU57-18x10.webp",18,10,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/vipexperiences.mx\/it\/author\/soporte_4z6oqe9k\/"},"uagb_comment_info":0,"uagb_excerpt":"A finales de la semana pasada, la casa italiana festej\u00f3 su aniversario con la presentaci\u00f3n de la colecci\u00f3n Ermenegildo Zegna XXX summer 2021. Reconocida, no s\u00f3lo por revolucionar la industria de la moda, sino tambi\u00e9n por su impecable sastrer\u00eda, el concepto de la nueva colecci\u00f3n es \u201cUse The Existing\u201d, para concientizar la responsabilidad social y&hellip;","_links":{"self":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/posts\/69325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/comments?post=69325"}],"version-history":[{"count":0,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/posts\/69325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/media\/55453"}],"wp:attachment":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/media?parent=69325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/categories?post=69325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/tags?post=69325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}