{"id":68785,"date":"2020-05-21T00:00:00","date_gmt":"2020-05-21T00:00:00","guid":{"rendered":"https:\/\/vipexperiences.mx\/petroleo-mexicano-repunta-y-recupera-su-precio-previo-a-covid-19\/"},"modified":"2020-05-21T00:00:00","modified_gmt":"2020-05-21T00:00:00","slug":"petroleo-mexicano-repunta-y-recupera-su-precio-previo-a-covid-19","status":"publish","type":"post","link":"https:\/\/vipexperiences.mx\/it\/2020\/05\/21\/petroleo-mexicano-repunta-y-recupera-su-precio-previo-a-covid-19\/","title":{"rendered":"Petr\u00f3leo mexicano repunta y recupera su precio previo a COVID-19"},"content":{"rendered":"<p><em>Fotos: Pixabay<\/em><\/p>\n<p>La tarde de este lunes, <a href=\"https:\/\/www.pemex.com\/Paginas\/default.aspx\" target=\"_blank\" rel=\"noopener\"><strong>Petr\u00f3leos Mexicanos<\/strong> <\/a>(Pemex) inform\u00f3 que el precio de la petr\u00f3leo<strong> se vendi\u00f3 en 26.73 d\u00f3lares por barril<\/strong>, con lo que repunt\u00f3 su nivel y se recuper\u00f3 previo a la pandemia del COVID-19.<\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/it\/2020\/04\/02\/grupo-hersa-el-aliado-que-toda-empresa-necesita\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-7137 size-thumbnail\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/04\/ANUNCIO-GRUPO-HERSA-367x400.jpg\" alt=\"\" width=\"367\" height=\"400\" \/><\/a>Con ello, el petr\u00f3leo mexicano <strong>multiplic\u00f3 su precio durante las \u00faltimas semanas.<\/strong><\/p>\n<p>Reflej\u00f3 una cotizaci\u00f3n que <strong>s\u00f3lo se hab\u00eda visto antes de declararse la pandemia<\/strong> por la Organizaci\u00f3n Mundial de la Salud (OMS).<\/p>\n<p>Adem\u00e1s, la mezcla mexicana tambi\u00e9n <strong>se vendi\u00f3 ocho% m\u00e1s (o 1.99 unidades) que a finales de la semana pasada.<\/strong><\/p>\n<p>Lo que represent\u00f3 la cotizaci\u00f3n m\u00e1s alta desde el 10 de marzo.<\/p>\n<p>En aquella fecha, se vendi\u00f3 en 27.40 d\u00f3lares y la pandemia, as\u00ed como la correspondiente contingencia,<strong> apenas comenzaban a tener consecuencias<\/strong>.<\/p>\n<p>Por otra parte, fue hace una semana que <strong>Pemex tambi\u00e9n confirm\u00f3 835 casos de COVID-19 en la empresa<\/strong>, de los cuales<strong> 102 han fallecido<\/strong> hasta la fecha.<\/p>\n<p><strong>Tambi\u00e9n indic\u00f3 que de los casos positivos,<\/strong> 343 fueron dados de alta, 229 contin\u00faan en aislamiento domiciliario,127 en hospitalizaci\u00f3n en un pabell\u00f3n aislado y 34 se encuentran en terapia intensiva.<\/p>\n<p>\u201c<em>Lamentablemente hasta esta fecha se han registrado 102 defunciones, de las cuales 41 ocurrieron en jubilados, 30 en familiares, 30 trabajadores y un externo\u201d, <\/em><strong>precis\u00f3 la petrolera nacional<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-8872\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/05\/oil-rig-2191711_1280.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/p>\n<h6>POTREBBE INTERESSARTI ANCHE:<\/h6>\n<p><a href=\"https:\/\/vipexperiences.mx\/it\/2020\/05\/18\/peso-mexicano-entre-el-regreso-a-la-normalidad-y-tensiones-politicas-internacionales\/\">PESO MEXICANO: ENTRE EL REGRESO A LA NORMALIDAD Y TENSIONES POL\u00cdTICAS<\/a><\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/it\/2020\/05\/17\/crece-el-comercio-electronico-en-mexico\/\">CRECE EL COMERCIO ELECTR\u00d3NICO EN M\u00c9XICO<\/a><\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/it\/2020\/05\/19\/eua-camara-de-representantes-aprueba-plan-de-alivio-economico\/\">EUA: C\u00c1MARA DE REPRESENTANTES APRUEBA PLAN DE ALIVIO ECON\u00d3MICO<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Fotos: Pixabay La tarde de este lunes, Petr\u00f3leos Mexicanos (Pemex) inform\u00f3 que el precio de la petr\u00f3leo se vendi\u00f3 en 26.73 d\u00f3lares por barril, con lo que repunt\u00f3 su nivel y se recuper\u00f3 previo a la pandemia del COVID-19. Con ello, el petr\u00f3leo mexicano multiplic\u00f3 su precio durante las \u00faltimas semanas. Reflej\u00f3 una cotizaci\u00f3n que &#8230; <a title=\"Petr\u00f3leo mexicano repunta y recupera su precio previo a COVID-19\" class=\"read-more\" href=\"https:\/\/vipexperiences.mx\/it\/2020\/05\/21\/petroleo-mexicano-repunta-y-recupera-su-precio-previo-a-covid-19\/\" aria-label=\"Per saperne di pi\u00f9 su Petr\u00f3leo mexicano repunta y recupera su precio previo a COVID-19\">Leggi tutto<\/a><\/p>","protected":false},"author":1,"featured_media":53309,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[20],"tags":[1693,1948,252,2011,2907,2908,46],"class_list":["post-68785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","tag-coronavirus","tag-covid-19","tag-mexico","tag-pandemia","tag-pemex","tag-petroleos-mexicanos","tag-tendencias"],"uagb_featured_image_src":{"full":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/petrol-996617_1280-jpg.webp",1280,852,false],"thumbnail":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/petrol-996617_1280-150x150.webp",150,150,true],"medium":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/petrol-996617_1280-300x200.webp",300,200,true],"medium_large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/petrol-996617_1280-768x511.webp",768,511,true],"large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/petrol-996617_1280-1024x682.webp",1024,682,true],"1536x1536":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/petrol-996617_1280-jpg.webp",1280,852,false],"2048x2048":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/petrol-996617_1280-jpg.webp",1280,852,false],"trp-custom-language-flag":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/petrol-996617_1280-18x12.webp",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/vipexperiences.mx\/it\/author\/soporte_4z6oqe9k\/"},"uagb_comment_info":0,"uagb_excerpt":"Fotos: Pixabay La tarde de este lunes, Petr\u00f3leos Mexicanos (Pemex) inform\u00f3 que el precio de la petr\u00f3leo se vendi\u00f3 en 26.73 d\u00f3lares por barril, con lo que repunt\u00f3 su nivel y se recuper\u00f3 previo a la pandemia del COVID-19. Con ello, el petr\u00f3leo mexicano multiplic\u00f3 su precio durante las \u00faltimas semanas. Reflej\u00f3 una cotizaci\u00f3n que&hellip;","_links":{"self":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/posts\/68785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/comments?post=68785"}],"version-history":[{"count":0,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/posts\/68785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/media\/53309"}],"wp:attachment":[{"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/media?parent=68785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/categories?post=68785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipexperiences.mx\/it\/wp-json\/wp\/v2\/tags?post=68785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}