{"id":70953,"date":"2021-02-11T00:00:00","date_gmt":"2021-02-11T00:00:00","guid":{"rendered":"https:\/\/vipexperiences.mx\/hyundai-presenta-el-vehiculo-de-movilidad-tiger\/"},"modified":"2021-02-11T00:00:00","modified_gmt":"2021-02-11T00:00:00","slug":"hyundai-presenta-el-vehiculo-de-movilidad-tiger","status":"publish","type":"post","link":"https:\/\/vipexperiences.mx\/de\/2021\/02\/11\/hyundai-presenta-el-vehiculo-de-movilidad-tiger\/","title":{"rendered":"Hyundai presenta el veh\u00edculo de movilidad TIGER"},"content":{"rendered":"<p>Hyundai Motor Group ha revelado TIGER (Robot Transformador de Excursi\u00f3n en Tierra Inteligente, por sus siglas en ingl\u00e9s), el segundo Veh\u00edculo de M\u00e1xima Movilidad (UMV) de la compa\u00f1\u00eda y el primero dise\u00f1ado para conducirse sin tripulaci\u00f3n.<\/p>\n<p>El robot transformador de excursi\u00f3n en tierra inteligente est\u00e1 dise\u00f1ado para transportar varios tipos de carga \u00fatil mientras viaja por terrenos desafiantes.<\/p>\n<p>TIGER est\u00e1 siendo desarrollado en el New Horizons Studio de Hyundai Motor Group (con sede en Mountain View, California), establecido a finales de 2020 para desarrollar UMV inspirado en el liderazgo en investigaci\u00f3n e innovaci\u00f3n de Silicon Valley y otros centros de innovaci\u00f3n.<\/p>\n<p>\u201cLos veh\u00edculos como TIGER y las tecnolog\u00edas que lo sustentan nos brindan la oportunidad de impulsar nuestra imaginaci\u00f3n\u201d, dijo el Dr. John Suh, Director de New Horizons Studio. \u201cBuscamos constantemente formas de repensar el dise\u00f1o y desarrollo de veh\u00edculos y redefinir el futuro del transporte y la movilidad\u201d.<\/p>\n<figure id=\"attachment_23338\" aria-describedby=\"caption-attachment-23338\" style=\"width: 1190px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-23338\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2021\/02\/Tiger-01.jpg\" alt=\"\" width=\"1200\" height=\"675\" \/><figcaption id=\"caption-attachment-23338\" class=\"wp-caption-text\">Foto: Hyundai.<\/figcaption><\/figure>\n<h6>El veh\u00edculo conceptual muestra su capacidad en terrenos remotos e inaccesibles<\/h6>\n<p>Las capacidades excepcionales de TIGER est\u00e1n dise\u00f1adas para funcionar como una plataforma de exploraci\u00f3n cient\u00edfica m\u00f3vil en lugares extremos y remotos. Basado en una arquitectura de plataforma modular, sus caracter\u00edsticas incluyen un sofisticado sistema de locomoci\u00f3n de piernas y ruedas, control direccional de 360 \u200b\u200bgrados y una gama de sensores para observaci\u00f3n remota. Tambi\u00e9n est\u00e1 destinado a conectarse a veh\u00edculos a\u00e9reos no tripulados (UAV) que pueden cargar y entregar TIGER a lugares inaccesibles.<\/p>\n<p>Con un gran espacio de carga alojado dentro de su cuerpo, TIGER puede transportar mercanc\u00edas para su entrega o desplegarse para entregar paquetes de ayuda en situaciones de emergencia. La articulaci\u00f3n pierna-rueda permite a TIGER abordar una variedad de situaciones extremas mientras mantiene la carga \u00fatil m\u00e1s nivelada que un veh\u00edculo terrestre t\u00edpico.<\/p>\n<p>Con las piernas retra\u00eddas, TIGER se conduce como un veh\u00edculo de tracci\u00f3n en las cuatro ruedas en su modo m\u00e1s eficiente. Cuando el veh\u00edculo se atasca o necesita viajar sobre un terreno que es dif\u00edcil o infranqueable para las ruedas, usa su capacidad para caminar, despegarse o viajar m\u00e1s f\u00e1cilmente sobre ese terreno.<\/p>\n<p>Esta caracter\u00edstica fue vista anteriormente en Elevate, el primer concepto de UMV de Hyundai Motor Group con patas m\u00f3viles, que debut\u00f3 en el Consumer Electronic Show (CES) de 2019. TIGER, comparte con este \u00faltimo caracter\u00edsticas similares en sus patas y ruedas. La diferencia entre Elevate y TIGER es que, mientras que el primero puede transportar pasajeros, el segundo no est\u00e1 dise\u00f1ado para ser tripulado. Tanto TIGER como Elevate combinan tecnolog\u00edas de locomoci\u00f3n rob\u00f3tica y con ruedas que les permite atravesar terrenos m\u00e1s all\u00e1 de lo que un veh\u00edculo todoterreno es capaz.<\/p>\n<figure id=\"attachment_23340\" aria-describedby=\"caption-attachment-23340\" style=\"width: 1190px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-23340\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2021\/02\/Tiger-04.jpg\" alt=\"\" width=\"1200\" height=\"675\" \/><figcaption id=\"caption-attachment-23340\" class=\"wp-caption-text\">Foto: Hyundai.<\/figcaption><\/figure>\n<h6>Primera versi\u00f3n dise\u00f1ada en Silicon Valley con asociaciones de desarrollo global<\/h6>\n<p>La primera versi\u00f3n de TIGER, X-1 \u2014la X significa experimental\u2014, re\u00fane una amplia gama de conocimientos tecnol\u00f3gicos y de dise\u00f1o. El proyecto est\u00e1 liderado por New Horizons Studio de Hyundai Motor Group en estrecha colaboraci\u00f3n con Autodesk, una empresa l\u00edder en software de dise\u00f1o de ingenier\u00eda.<\/p>\n<p>\u201cTrabajar en estrecha colaboraci\u00f3n con el equipo de Hyundai en el veh\u00edculo TIGER X-1, utilizando tecnolog\u00eda avanzada como el dise\u00f1o generativo para traspasar los l\u00edmites del aumento de la fuerza y \u200b\u200bal mismo tiempo reducir el peso en el transporte, es exactamente lo que queremos decir cuando hablamos de crear lo nuevo posible\u201d, dijo Srinath Jonnalagadda, Vicepresidente de Estrategia Comercial para dise\u00f1o y fabricaci\u00f3n de Autodesk. \u00abLas nuevas t\u00e9cnicas de dise\u00f1o, ingenier\u00eda y fabricaci\u00f3n habilitadas por Autodesk Fusion 360 ayudan a los equipos colaborativos modernos de hoy a llegar a la producci\u00f3n de manera m\u00e1s r\u00e1pida y eficiente\u00bb.<\/p>\n<p>TIGER X-1 fusiona las capacidades de dise\u00f1o generativo de Autodesk con las crecientes capacidades de investigaci\u00f3n y desarrollo de Hyundai en movilidad. Los equipos han estado trabajando en conjunto para crear una estructura liviana pero incre\u00edblemente fuerte, con las patas y ciertos elementos del chasis creados con impresi\u00f3n aditiva compuesta de fibra de carbono.<\/p>\n<p>New Horizons Studio en colaboraci\u00f3n con Sundberg-Ferar, expertos en dise\u00f1o de conceptos, ha desarrollado TIGER X-1 con la finalidad de entregar y recuperar cargas \u00fatiles cr\u00edticas en terrenos accidentados. Estas capacidades hacen que el veh\u00edculo conceptual sea ideal para la evaluaci\u00f3n de la superficie de 360 \u200b\u200bgrados en \u00e1reas afectadas por desastres naturales, terrenos desafiantes, o incluso la superficie de la luna o alg\u00fan planeta.<\/p>\n<figure id=\"attachment_23341\" aria-describedby=\"caption-attachment-23341\" style=\"width: 1190px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-23341\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2021\/02\/Tiger-03.jpg\" alt=\"\" width=\"1200\" height=\"800\" \/><figcaption id=\"caption-attachment-23341\" class=\"wp-caption-text\">Foto: Hyundai.<\/figcaption><\/figure>\n<p><strong>K\u00d6NNTEN SIE AUCH INTERESSIERT SEIN AN:<\/strong><br \/>\n<a href=\"https:\/\/vipexperiences.mx\/de\/2021\/02\/10\/mini-electric-collection-para-cooper-se-el-divertido-manejo-de-un-electrico\/\">MINI ELECTRIC COLLECTION PARA COOPER SE, EL DIVERTIDO MANEJO DE UN EL\u00c9CTRICO<\/a><br \/>\n<a href=\"https:\/\/vipexperiences.mx\/de\/2021\/02\/10\/bvlgari-octo-finissimo-las-nuevas-facetas-de-la-estetica-della-meccanica\/\">BVLGARI OCTO FINISSIMO, LAS NUEVAS FACETAS DE LA \u2018ESTETICA DELLA MECCANICA\u2019<\/a><br \/>\n<a href=\"https:\/\/vipexperiences.mx\/de\/2021\/02\/09\/jaguar-i-pace-impone-record-de-velocidad-en-interlagos\/\">JAGUAR I-PACE IMPONE R\u00c9CORD DE VELOCIDAD EN INTERLAGOS<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Hyundai Motor Group ha revelado TIGER (Robot Transformador de Excursi\u00f3n en Tierra Inteligente, por sus siglas en ingl\u00e9s), el segundo Veh\u00edculo de M\u00e1xima Movilidad (UMV) de la compa\u00f1\u00eda y el primero dise\u00f1ado para conducirse sin tripulaci\u00f3n. El robot transformador de excursi\u00f3n en tierra inteligente est\u00e1 dise\u00f1ado para transportar varios tipos de carga \u00fatil mientras viaja &#8230; <a title=\"Hyundai presenta el veh\u00edculo de movilidad TIGER\" class=\"read-more\" href=\"https:\/\/vipexperiences.mx\/de\/2021\/02\/11\/hyundai-presenta-el-vehiculo-de-movilidad-tiger\/\" aria-label=\"Mehr Informationen \u00fcber Hyundai presenta el veh\u00edculo de movilidad TIGER\">Weiterlesen<\/a><\/p>","protected":false},"author":1,"featured_media":61490,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[9],"tags":[191,1051,1444,46,4433],"class_list":["post-70953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-motor","tag-concepto","tag-hyundai","tag-movilidad","tag-tendencias","tag-tiger"],"uagb_featured_image_src":{"full":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Tiger-02-jpg.webp",1200,675,false],"thumbnail":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Tiger-02-150x150.webp",150,150,true],"medium":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Tiger-02-300x169.webp",300,169,true],"medium_large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Tiger-02-768x432.webp",768,432,true],"large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Tiger-02-1024x576.webp",1024,576,true],"1536x1536":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Tiger-02-jpg.webp",1200,675,false],"2048x2048":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Tiger-02-jpg.webp",1200,675,false],"trp-custom-language-flag":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Tiger-02-18x10.webp",18,10,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/vipexperiences.mx\/de\/author\/soporte_4z6oqe9k\/"},"uagb_comment_info":0,"uagb_excerpt":"Hyundai Motor Group ha revelado TIGER (Robot Transformador de Excursi\u00f3n en Tierra Inteligente, por sus siglas en ingl\u00e9s), el segundo Veh\u00edculo de M\u00e1xima Movilidad (UMV) de la compa\u00f1\u00eda y el primero dise\u00f1ado para conducirse sin tripulaci\u00f3n. El robot transformador de excursi\u00f3n en tierra inteligente est\u00e1 dise\u00f1ado para transportar varios tipos de carga \u00fatil mientras viaja&hellip;","_links":{"self":[{"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/posts\/70953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/comments?post=70953"}],"version-history":[{"count":0,"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/posts\/70953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/media\/61490"}],"wp:attachment":[{"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/media?parent=70953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/categories?post=70953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipexperiences.mx\/de\/wp-json\/wp\/v2\/tags?post=70953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}