{"id":70347,"date":"2020-11-19T00:00:00","date_gmt":"2020-11-19T00:00:00","guid":{"rendered":"https:\/\/vipexperiences.mx\/lg-presenta-nueva-serie-de-smartphones\/"},"modified":"2020-11-19T00:00:00","modified_gmt":"2020-11-19T00:00:00","slug":"lg-presenta-nueva-serie-de-smartphones","status":"publish","type":"post","link":"https:\/\/vipexperiences.mx\/ar\/2020\/11\/19\/lg-presenta-nueva-serie-de-smartphones\/","title":{"rendered":"LG presenta nueva serie de smartphones"},"content":{"rendered":"<p>LG Electronics present\u00f3 la nueva l\u00ednea de smartphones serie K 2020 para ofrecer un dise\u00f1o premium con caracter\u00edsticas y funcionalidades mejoradas a precios asequibles.<br \/>\nLa nueva serie K est\u00e1 integrada por los modelos LG K42, LG K52 y LG K62, que sorprenden por su elegante dise\u00f1o y a la vez cubren las necesidades de un amplio sector de usuarios.<\/p>\n<p><strong>As\u00ed es la Serie K<\/strong><\/p>\n<p>En cuanto a su est\u00e9tica, en K42 destaca un patr\u00f3n de ondas \u00fanico que parece cambiar de color, mientras que un recubrimiento especial se suma a la est\u00e9tica del dispositivo para protegerlo contra raspaduras y rasgu\u00f1os; mientras que en los otros dos equipos el acabado mate crea un patr\u00f3n \u00f3ptico \u00fanico para disimular las huellas dactilares. Los tres tel\u00e9fonos se presentan en una gama de atractivos colores que complementan sus elegantes dise\u00f1os.<\/p>\n<figure id=\"attachment_19696\" aria-describedby=\"caption-attachment-19696\" style=\"width: 416px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-19696\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/11\/LG-K52_04.jpg\" alt=\"\" width=\"426\" height=\"448\" \/><figcaption id=\"caption-attachment-19696\" class=\"wp-caption-text\">Imagen: LG<\/figcaption><\/figure>\n<p>Las pantallas mejoradas de los tel\u00e9fonos de esta serie ofrecen una visualizaci\u00f3n cinematogr\u00e1fica \u00fanica en cada modelo gracias a la pantalla con resoluci\u00f3n HD+ de 6.6 pulgadas con una relaci\u00f3n de aspecto de 20:9, con una c\u00e1mara frontal se oculta a trav\u00e9s de un peque\u00f1o orificio y permite que la parte frontal de los tel\u00e9fonos quede rodeada por biseles delgados y discretos.<\/p>\n<p>En cuanto al audio, LG 3D Sound Engine agrega una mayor sensaci\u00f3n de inmersi\u00f3n tanto a K52 como a K62, ofreciendo sonidos aut\u00e9nticos y detallados, optimizados gracias a inteligencia artificial.<\/p>\n<p><strong>Sistema penta-c\u00e1mara que da una nueva identidad<\/strong><\/p>\n<p>Con cuatro lentes traseros de alta calidad en forma de isla, adem\u00e1s de la c\u00e1mara frontal, los nuevos dispositivos de la serie K ofrecen una experiencia de creaci\u00f3n de contenido comparable con los smartphones m\u00e1s costosos del mercado.<\/p>\n<p>K52 y K62 cuentan con c\u00e1maras principales de 48 MP que capturan fotos y videos m\u00e1s brillantes y n\u00edtidos, mientras que el K42 cuenta con un excelente lente principal de 13 MP.<\/p>\n<p><a href=\"http:\/\/cornertech.mx\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13556\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/anuncio-Corner-B-agosto-202.jpg\" sizes=\"(max-width: 728px) 100vw, 728px\" srcset=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/anuncio-Corner-B-agosto-202.jpg 728w, https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/anuncio-Corner-B-agosto-202-400x123.jpg 400w\" alt=\"\" width=\"728\" height=\"224\" \/><\/a><\/p>\n<p>La c\u00e1mara frontal de 28 MP del K62 permite tomar selfies de gran calidad con efectos art\u00edsticos de desenfoque, mientras que el lente macro de los tres modelos puede capturar primeros planos magn\u00edficamente detallados sin necesidad de hacer zoom.<\/p>\n<p>Gracias al sensor PDAF las im\u00e1genes capturadas ser\u00e1n m\u00e1s claras incluso en movimiento, adem\u00e1s, por medio de la tecnolog\u00eda Quad-Cell las fotos en K52 y K62 ser\u00e1n m\u00e1s brillantes y claras incluso en condiciones de poca luz con la tecnolog\u00eda de agrupaci\u00f3n de pixeles.<\/p>\n<figure id=\"attachment_19697\" aria-describedby=\"caption-attachment-19697\" style=\"width: 533px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-19697\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/11\/LG-K62_02.jpg\" alt=\"\" width=\"543\" height=\"571\" \/><figcaption id=\"caption-attachment-19697\" class=\"wp-caption-text\">Imagen: LG<\/figcaption><\/figure>\n<p>En temas de conectividad, los modelos K52 y K62 tienen la capacidad de conectarse a la banda de 5GHz del modem para que el contenido se descargue y reproduzca con mayor rapidez que otros modelos que no tienen esta funci\u00f3n, y con el est\u00e1ndar de comunicaci\u00f3n Bluetooth la distancia de transmisi\u00f3n se ampl\u00eda 4 veces, de 10 a 40 metros.<\/p>\n<p><strong>Precios y disponibilidad<\/strong><\/p>\n<p>La nueva Serie K de LG est\u00e1 disponible en toda la Rep\u00fablica Mexicana a partir de hoy con los siguientes costos recomendados: LG K42 $5,499, LG K52 $6,269 y LG K62 $6,999.<\/p>\n<p><strong>\u0642\u062f \u062a\u0643\u0648\u0646 \u0645\u0647\u062a\u0645\u064b\u0627 \u0623\u064a\u0636\u064b\u0627 \u0628\u0640<\/strong><\/p>\n<p><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/vipexperiences.mx\/ar\/2020\/04\/24\/apps-para-relajarte-en-esta-cuarentena\/\">APPS PARA RELAJARTE EN ESTA CUARENTENA<\/a><\/span><\/p>\n<p><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/vipexperiences.mx\/ar\/2020\/04\/22\/las-mejores-aplicaciones-para-ser-el-mejor-en-la-cocina\/\">LAS MEJORES APLICACIONES PARA SER EL MEJOR EN LA COCINA<\/a><\/span><\/p>\n<p><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/vipexperiences.mx\/ar\/2020\/04\/16\/esta-es-la-aplicacion-de-videollamadas-que-utiliza-la-onu\/\">ESTA ES LA APLICACI\u00d3N DE VIDEOLLAMADAS QUE UTILIZA LA ONU<\/a><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>LG Electronics present\u00f3 la nueva l\u00ednea de smartphones serie K 2020 para ofrecer un dise\u00f1o premium con caracter\u00edsticas y funcionalidades mejoradas a precios asequibles. La nueva serie K est\u00e1 integrada por los modelos LG K42, LG K52 y LG K62, que sorprenden por su elegante dise\u00f1o y a la vez cubren las necesidades de un &#8230; <a title=\"LG presenta nueva serie de smartphones\" class=\"read-more\" href=\"https:\/\/vipexperiences.mx\/ar\/2020\/11\/19\/lg-presenta-nueva-serie-de-smartphones\/\" aria-label=\"Read more about LG presenta nueva serie de smartphones\">\u0627\u0644\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f<\/a><\/p>","protected":false},"author":1,"featured_media":59359,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[21],"tags":[2196,493,4898,46],"class_list":["post-70347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luxury-lifestyle","tag-tech","tag-tecnologia","tag-telefonos-celulares","tag-tendencias"],"uagb_featured_image_src":{"full":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/K-series_Range-Shot_01-1-jpg.webp",1600,1180,false],"thumbnail":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/K-series_Range-Shot_01-1-150x150.webp",150,150,true],"medium":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/K-series_Range-Shot_01-1-300x221.webp",300,221,true],"medium_large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/K-series_Range-Shot_01-1-768x566.webp",768,566,true],"large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/K-series_Range-Shot_01-1-1024x755.webp",1024,755,true],"1536x1536":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/K-series_Range-Shot_01-1-1536x1133.webp",1536,1133,true],"2048x2048":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/K-series_Range-Shot_01-1-jpg.webp",1600,1180,false],"trp-custom-language-flag":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/K-series_Range-Shot_01-1-16x12.webp",16,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/vipexperiences.mx\/ar\/author\/soporte_4z6oqe9k\/"},"uagb_comment_info":0,"uagb_excerpt":"LG Electronics present\u00f3 la nueva l\u00ednea de smartphones serie K 2020 para ofrecer un dise\u00f1o premium con caracter\u00edsticas y funcionalidades mejoradas a precios asequibles. La nueva serie K est\u00e1 integrada por los modelos LG K42, LG K52 y LG K62, que sorprenden por su elegante dise\u00f1o y a la vez cubren las necesidades de un&hellip;","_links":{"self":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/posts\/70347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/comments?post=70347"}],"version-history":[{"count":0,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/posts\/70347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/media\/59359"}],"wp:attachment":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/media?parent=70347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/categories?post=70347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/tags?post=70347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}