{"id":69592,"date":"2020-08-20T00:00:00","date_gmt":"2020-08-20T00:00:00","guid":{"rendered":"https:\/\/vipexperiences.mx\/blackberry-presentara-nuevos-smartphones\/"},"modified":"2020-08-20T00:00:00","modified_gmt":"2020-08-20T00:00:00","slug":"blackberry-presentara-nuevos-smartphones","status":"publish","type":"post","link":"https:\/\/vipexperiences.mx\/ar\/2020\/08\/20\/blackberry-presentara-nuevos-smartphones\/","title":{"rendered":"BlackBerry presentar\u00e1 nuevos smartphones"},"content":{"rendered":"<p>Es innegable que los m\u00f3viles de BlackBerry fueron un parteaguas, logrando un antes y un despu\u00e9s en el mundo de los tel\u00e9fonos inteligentes, pero debido a su nula evoluci\u00f3n y crecimiento del sistema operativo Android perdieron popularidad algunos a\u00f1os atr\u00e1s.<\/p>\n<p>Despu\u00e9s, la marca china TCL la adquiri\u00f3 en 2016 y relanz\u00f3 nuevos m\u00f3viles como el m\u00e1s reciente, BlackBerry KEY2 LE, que no alcanzaron las ventas proyectadas logrando as\u00ed el t\u00e9rmino de su producci\u00f3n.<\/p>\n<p>Pero BlackBerry no est\u00e1 lista para morir, y ahora busca una nueva oportunidad para conquistar el mercado actual, presentando nuevos modelos con teclado f\u00edsico QWERTY, tecnolog\u00eda 5G y caracter\u00edsticas con las que podr\u00eda competir con los m\u00f3viles m\u00e1s vendidos.<\/p>\n<p>Sin embargo, estos equipos no ser\u00e1n fabricados por BlackBerry, sino que permitir\u00e1 el uso de su nombre e imagen para que FIH Mobile, subsidiaria de Foxconn, y Onward Mobility, l\u00edder en seguridad m\u00f3vil, elaboren esta nueva l\u00ednea.<\/p>\n<p>\u00abBlackBerry est\u00e1 encantado de que OnwardMobility entregar\u00e1 un smartphone BlackBerry con teclado f\u00edsico y 5G, que aproveche nuestros altos est\u00e1ndares de confianza y seguridad, sin\u00f3nimos de nuestra marca\u00bb, dio a conocer en un comunicado Jonh Chen, CEO y presidente de BlackBerry.<\/p>\n<p>Estos nuevos y propositivos m\u00f3viles contar\u00e1n con sistema operativo Android, ya presente en los dispositivos fabricados por TCL a\u00f1os atr\u00e1s, y se espera que cuenten con un apartado fotogr\u00e1fico de gama alta y un excelente procesador.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-14623\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/08\/1366_2000-1.png\" alt=\"\" width=\"643\" height=\"482\" \/><\/p>\n<p><strong>Disponibilidad<\/strong><\/p>\n<p>Tambi\u00e9n se ha comunicado que si todo sale bien, el dispositivo firmado por BlackBerry estar\u00eda disponibles en mercados como Europa y Norteam\u00e9rica en la primera mitad del siguiente a\u00f1o.<\/p>\n<h6>\u0642\u062f \u062a\u0643\u0648\u0646 \u0645\u0647\u062a\u0645\u064b\u0627 \u0623\u064a\u0636\u064b\u0627 \u0628\u0640<\/h6>\n<p><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/vipexperiences.mx\/ar\/2020\/04\/21\/asi-es-el-popular-lg-q6-prime\/\">\u0643\u064a\u0641 \u064a\u0628\u062f\u0648 \u0647\u0627\u062a\u0641 lg q6 Prime \u0627\u0644\u0634\u0647\u064a\u0631<\/a><\/span><\/p>\n<p><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/vipexperiences.mx\/ar\/2020\/04\/21\/7104\/\">\u0628\u0648\u0644\u0627\u0631\u0648\u064a\u062f \u0627\u0644\u0622\u0646\u060c \u0630\u0643\u0631\u064a\u0627\u062a \u0628\u0637\u0627\u0628\u0639 \u0627\u0644\u0645\u062f\u0631\u0633\u0629 \u0627\u0644\u0642\u062f\u064a\u0645\u0629<\/a><\/span><\/p>\n<p><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/marshall%20presenta%20bocina%20con%20soporte%20de%20voz%20alexa\/\">\u0645\u0627\u0631\u0634\u0627\u0644 \u062a\u0637\u0631\u062d \u0645\u0643\u0628\u0631 \u0635\u0648\u062a \u0645\u0627\u0631\u0634\u0627\u0644 \u0645\u0639 \u062f\u0639\u0645 \u0635\u0648\u062a \u0623\u0644\u064a\u0643\u0633\u0627<\/a><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Es innegable que los m\u00f3viles de BlackBerry fueron un parteaguas, logrando un antes y un despu\u00e9s en el mundo de los tel\u00e9fonos inteligentes, pero debido a su nula evoluci\u00f3n y crecimiento del sistema operativo Android perdieron popularidad algunos a\u00f1os atr\u00e1s. Despu\u00e9s, la marca china TCL la adquiri\u00f3 en 2016 y relanz\u00f3 nuevos m\u00f3viles como el &#8230; <a title=\"BlackBerry presentar\u00e1 nuevos smartphones\" class=\"read-more\" href=\"https:\/\/vipexperiences.mx\/ar\/2020\/08\/20\/blackberry-presentara-nuevos-smartphones\/\" aria-label=\"Read more about BlackBerry presentar\u00e1 nuevos smartphones\">\u0627\u0644\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f<\/a><\/p>","protected":false},"author":1,"featured_media":56507,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[21],"tags":[4402,738,1316,46],"class_list":["post-69592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luxury-lifestyle","tag-blackberry","tag-smartphone","tag-telefono-inteligente","tag-tendencias"],"uagb_featured_image_src":{"full":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/blackberry-2690103_1280-jpg.webp",1280,853,false],"thumbnail":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/blackberry-2690103_1280-150x150.webp",150,150,true],"medium":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/blackberry-2690103_1280-300x200.webp",300,200,true],"medium_large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/blackberry-2690103_1280-768x512.webp",768,512,true],"large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/blackberry-2690103_1280-1024x682.webp",1024,682,true],"1536x1536":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/blackberry-2690103_1280-jpg.webp",1280,853,false],"2048x2048":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/blackberry-2690103_1280-jpg.webp",1280,853,false],"trp-custom-language-flag":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/blackberry-2690103_1280-18x12.webp",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/vipexperiences.mx\/ar\/author\/soporte_4z6oqe9k\/"},"uagb_comment_info":0,"uagb_excerpt":"Es innegable que los m\u00f3viles de BlackBerry fueron un parteaguas, logrando un antes y un despu\u00e9s en el mundo de los tel\u00e9fonos inteligentes, pero debido a su nula evoluci\u00f3n y crecimiento del sistema operativo Android perdieron popularidad algunos a\u00f1os atr\u00e1s. Despu\u00e9s, la marca china TCL la adquiri\u00f3 en 2016 y relanz\u00f3 nuevos m\u00f3viles como el&hellip;","_links":{"self":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/posts\/69592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/comments?post=69592"}],"version-history":[{"count":0,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/posts\/69592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/media\/56507"}],"wp:attachment":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/media?parent=69592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/categories?post=69592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/tags?post=69592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}