{"id":68570,"date":"2020-04-21T00:00:00","date_gmt":"2020-04-21T00:00:00","guid":{"rendered":"https:\/\/vipexperiences.mx\/7104-2\/"},"modified":"2020-04-21T00:00:00","modified_gmt":"2020-04-21T00:00:00","slug":"7104-2","status":"publish","type":"post","link":"https:\/\/vipexperiences.mx\/ar\/2020\/04\/21\/7104-2\/","title":{"rendered":"Polaroid Now, recuerdos con sello old school"},"content":{"rendered":"<p><a href=\"https:\/\/us.polaroid.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Polaroid<\/strong><\/a> contin\u00faa mejorando sus cl\u00e1sicas c\u00e1maras y ahora estrena un nuevo modelo, bautizado como <a href=\"https:\/\/us.polaroid.com\/products\/polaroid-now\" target=\"_blank\" rel=\"noopener\"><strong>Polaroid Now<\/strong><\/a>.<\/p>\n<p><strong>Est\u00e9ticamente<\/strong> no le pide nada a sus predecesoras, la <strong>OneStep2<\/strong> y <strong>OneStep Plus.<\/strong><\/p>\n<p>Por el contrario, es un modelo m\u00e1s limpio en cuanto al dise\u00f1o, pero que se compensa con <strong>detalles a colores<\/strong>, los cuales complacer\u00e1n a los fan\u00e1ticos.<\/p>\n<p>La <strong>Polaroid Now<\/strong> ofrece <strong>novedades interesantes,<\/strong> la primer es que tiene un sistema de enfoque autom\u00e1tico.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-7114 size-full\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/04\/Captura-de-Pantalla-2020-04-21-a-las-17.44.55.png\" alt=\"\" width=\"734\" height=\"496\" \/><\/p>\n<p>Detecta lo que va a capturar gracias a sus <strong>dos lentes<\/strong>, de 35mm y 40mm, los cuales se manipulan dependiendo de la distancia.<\/p>\n<p>Por supuesto que <strong>cuenta con un visor<\/strong> para realizar los encuadres, un toque distintivo de la marca y de la vieja escuela.<\/p>\n<p>Cuenta con un <strong>flash<\/strong>, en ese sentido, la marca <strong>empuj\u00f3 este rubro<\/strong>, ya que es tal vez el mejor que se ha manufacturado para sus modelos.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-7115 size-full\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/04\/Captura-de-Pantalla-2020-04-21-a-las-17.45.02.png\" alt=\"\" width=\"740\" height=\"495\" \/><\/p>\n<p>Polaroid asegura que es <strong>el m\u00e1s preciso y potente<\/strong>, detecta las <strong>condiciones de iluminaci\u00f3n<\/strong> para determinar la intensidad del disparo.<\/p>\n<p>Hay un <strong>bot\u00f3n para desactivarlo<\/strong> en caso de que no la luz natural sea suficiente.<\/p>\n<p>En cuanto a funciones, la Polaroid Now cuenta con opciones interesantes:<\/p>\n<p>La primera es que tiene una para obtener<strong> dos cuadros en una sola imagen<\/strong>, el tiempo de exposici\u00f3n de la foto.<\/p>\n<p>Si eres seguidor de la marca, algo que entusiasma es que <strong>ahora tiene timer<\/strong> para el disparo. Ahora podr\u00e1s salir en todas las fotos si as\u00ed lo deseas.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-7117 size-full\" src=\"https:\/\/vipexperiences.mx\/wp-content\/uploads\/2020\/04\/Captura-de-Pantalla-2020-04-21-a-las-17.45.16.png\" alt=\"\" width=\"738\" height=\"495\" \/><\/p>\n<p><strong>El timer le da nueves segundos<\/strong> al usuario para acomodarse en el encuadre.<\/p>\n<p>En cuanto a la pel\u00edcula, tienes la opci\u00f3n de comprar en<strong> blanco y negro o a color<\/strong> (i-Type), las cuales tardan en procesar la imagen unos 10 minutos.<\/p>\n<p>La <strong>bater\u00eda<\/strong> es recargable y cuenta con su <strong>cable USB.<\/strong> Su precio es de aproximadamente <a href=\"https:\/\/us.polaroid.com\/products\/polaroid-now\" target=\"_blank\" rel=\"noopener\"><strong>100 d\u00f3lares<\/strong><\/a>.<\/p>\n<p><strong>Mira este video<\/strong> en donde la marca presenta a Polaroid Now.<\/p>\n<p><iframe title=\"Polaroid Now - Real Connection\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/2aV3Iyyt2EM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h6>Tambi\u00e9n te puede interesar:<\/h6>\n<p><a href=\"https:\/\/vipexperiences.mx\/ar\/2020\/04\/21\/asi-es-el-popular-lg-q6-prime\/\">\u0643\u064a\u0641 \u064a\u0628\u062f\u0648 \u0647\u0627\u062a\u0641 lg q6 Prime \u0627\u0644\u0634\u0647\u064a\u0631<\/a><\/p>\n<p><a href=\"http:\/\/MARSHALL PRESENTA BOCINA CON SOPORTE DE VOZ ALEXA\">\u0645\u0627\u0631\u0634\u0627\u0644 \u062a\u0637\u0631\u062d \u0645\u0643\u0628\u0631 \u0635\u0648\u062a \u0645\u0627\u0631\u0634\u0627\u0644 \u0645\u0639 \u062f\u0639\u0645 \u0635\u0648\u062a \u0623\u0644\u064a\u0643\u0633\u0627<\/a><\/p>\n<p><a href=\"https:\/\/vipexperiences.mx\/ar\/2020\/04\/13\/huawei-p40-lite-llega-a-mexico\/\">HUAWEI P40 LITE LLEGA A M\u00c9XICO<\/a><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Polaroid contin\u00faa mejorando sus cl\u00e1sicas c\u00e1maras y ahora estrena un nuevo modelo, bautizado como Polaroid Now. Est\u00e9ticamente no le pide nada a sus predecesoras, la OneStep2 y OneStep Plus. Por el contrario, es un modelo m\u00e1s limpio en cuanto al dise\u00f1o, pero que se compensa con detalles a colores, los cuales complacer\u00e1n a los fan\u00e1ticos. &#8230; <a title=\"Polaroid Now, recuerdos con sello old school\" class=\"read-more\" href=\"https:\/\/vipexperiences.mx\/ar\/2020\/04\/21\/7104-2\/\" aria-label=\"Read more about Polaroid Now, recuerdos con sello old school\">\u0627\u0644\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f<\/a><\/p>","protected":false},"author":1,"featured_media":52412,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[21],"tags":[1117,2545,1978,1278,2546,2547,2196,493,46],"class_list":["post-68570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luxury-lifestyle","tag-camara","tag-camaras","tag-fotografia","tag-fotos","tag-polaroid","tag-polaroid-now","tag-tech","tag-tecnologia","tag-tendencias"],"uagb_featured_image_src":{"full":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Captura-de-Pantalla-2020-04-21-a-las-17.44.09.png",996,486,false],"thumbnail":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Captura-de-Pantalla-2020-04-21-a-las-17.44.09-150x150.png",150,150,true],"medium":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Captura-de-Pantalla-2020-04-21-a-las-17.44.09-300x146.png",300,146,true],"medium_large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Captura-de-Pantalla-2020-04-21-a-las-17.44.09-768x375.png",768,375,true],"large":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Captura-de-Pantalla-2020-04-21-a-las-17.44.09.png",996,486,false],"1536x1536":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Captura-de-Pantalla-2020-04-21-a-las-17.44.09.png",996,486,false],"2048x2048":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Captura-de-Pantalla-2020-04-21-a-las-17.44.09.png",996,486,false],"trp-custom-language-flag":["https:\/\/vipexperiences.mx\/wp-content\/uploads\/2024\/06\/Captura-de-Pantalla-2020-04-21-a-las-17.44.09-18x9.png",18,9,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/vipexperiences.mx\/ar\/author\/soporte_4z6oqe9k\/"},"uagb_comment_info":0,"uagb_excerpt":"Polaroid contin\u00faa mejorando sus cl\u00e1sicas c\u00e1maras y ahora estrena un nuevo modelo, bautizado como Polaroid Now. Est\u00e9ticamente no le pide nada a sus predecesoras, la OneStep2 y OneStep Plus. Por el contrario, es un modelo m\u00e1s limpio en cuanto al dise\u00f1o, pero que se compensa con detalles a colores, los cuales complacer\u00e1n a los fan\u00e1ticos.&hellip;","_links":{"self":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/posts\/68570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/comments?post=68570"}],"version-history":[{"count":0,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/posts\/68570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/media\/52412"}],"wp:attachment":[{"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/media?parent=68570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/categories?post=68570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipexperiences.mx\/ar\/wp-json\/wp\/v2\/tags?post=68570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}